{"id":2111,"date":"2020-10-10T14:01:06","date_gmt":"2020-10-10T12:01:06","guid":{"rendered":"https:\/\/cheries-cheris.com\/festival\/?post_type=film&#038;p=2111"},"modified":"2021-06-05T18:54:43","modified_gmt":"2021-06-05T16:54:43","slug":"saint-narcisse","status":"publish","type":"film","link":"https:\/\/cheries-cheris.com\/festival\/films\/saint-narcisse\/","title":{"rendered":"SAINT-NARCISSE"},"content":{"rendered":"<p>Dans les ann\u00e9es 1970, \u00e0 la mort de sa grand-m\u00e8re, le jeune, beau et narcissique Dominic trouve des lettres qui contredisent la version selon laquelle sa m\u00e8re serait morte en couches. S\u2019ensuit sa qu\u00eate pour la retrouver vivante, habitant au fond des bois avec la jeune et myst\u00e9rieuse Ir\u00e8ne. Des liens \u00e9tranges et forts se nouent entre ces trois-l\u00e0, mais les d\u00e9couvertes de Dominic ne s\u2019arr\u00eatent pas en si bon chemin puisqu\u2019il d\u00e9couvre aussi qu\u2019il a un fr\u00e8re jumeau identique, Daniel, prisonnier d\u2019un monast\u00e8re et surtout des griffes d\u2019un pr\u00eatre qui ne lui veut pas que du bien\u2026<!--more--><\/p>\n<p><strong>Pr\u00e9sent\u00e9 \u00e0 la Mostra de Venise 2020, Saint Narcisse est le nouveau long m\u00e9trage du plus queer des Torontois Bruce LaBruce. Ce projet que le cin\u00e9aste avait en t\u00eate depuis un bon nombre d\u2019ann\u00e9es parle des retrouvailles de fr\u00e8res siamois s\u00e9par\u00e9s \u00e0 la naissance et qui d\u00e9cident \u00e0 la vingtaine &#8211; dans un \u00e9lan qui tient autant du mysticisme que du narcissisme sexuel &#8211; de se recoller. Variation libre sur le mythe de Narcisse, le film traite de th\u00e8mes comme la fluidit\u00e9 des identit\u00e9s, la masturbation, le twincest [inceste entre jumeaux ou jumelles, ndlr] et l\u2019intersection entre extase religieuse et sexuelle. Une \u0153uvre provocatrice, romantique et pleine d\u2019espoir !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans les ann\u00e9es 1970, \u00e0 la mort de sa grand-m\u00e8re, le jeune, beau et narcissique Dominic trouve des lettres qui contredisent la version selon laquelle sa m\u00e8re serait morte en couches. S\u2019ensuit sa qu\u00eate pour la retrouver vivante, habitant au fond des bois avec la jeune et myst\u00e9rieuse Ir\u00e8ne. Des liens \u00e9tranges et forts se [&hellip;]<\/p>\n","protected":false},"featured_media":2115,"template":"","meta":[],"film-type":[53,22],"film-tag":[],"class_list":["post-2111","film","type-film","status-publish","has-post-thumbnail","hentry","film-type-bruce-labruce","film-type-seances-speciales"],"_links":{"self":[{"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/film\/2111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/film"}],"about":[{"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/types\/film"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/media\/2115"}],"wp:attachment":[{"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/media?parent=2111"}],"wp:term":[{"taxonomy":"film-type","embeddable":true,"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/film-type?post=2111"},{"taxonomy":"film-tag","embeddable":true,"href":"https:\/\/cheries-cheris.com\/festival\/wp-json\/wp\/v2\/film-tag?post=2111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}